{"id":10059,"date":"2026-01-16T09:00:28","date_gmt":"2026-01-16T09:00:28","guid":{"rendered":"https:\/\/zango.co.ao\/?p=10059"},"modified":"2026-01-16T09:07:32","modified_gmt":"2026-01-16T09:07:32","slug":"patricia-faria-torna-se-membro-da-comunidade-internacional-visitor-leadership-program-ivlp-dos-eua","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2026\/01\/16\/patricia-faria-torna-se-membro-da-comunidade-internacional-visitor-leadership-program-ivlp-dos-eua\/","title":{"rendered":"Patr\u00edcia Faria Torna-se Membro da Comunidade Internacional Visitor Leadership Program (IVLP) dos EUA"},"content":{"rendered":"\n<p>A artista e advogada angolana Patr\u00edcia Faria integrou recentemente a comunidade International Visitor Leadership Program (IVLP), uma iniciativa de interc\u00e2mbio profissional promovida pelo Departamento de Estado dos Estados Unidos da Am\u00e9rica.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o foi avan\u00e7ada pela artista atrav\u00e9s das suas redes sociais, onde destacou que, por convite do Governo Norte-Americano, vivenciou a experi\u00eancia da cultura dos Estados Unidos da Am\u00e9rica durante tr\u00eas semanas e esteve ao servi\u00e7o da economia e do bem-estar social.<\/p>\n\n\n\n<p>A comunidade Internacional do IVLP \u00e9 composta por antigos participantes do programa oriundos de mais de 200 pa\u00edses, formando uma rede global de l\u00edderes, decisores e profissionais de refer\u00eancia nas \u00e1reas da pol\u00edtica, educa\u00e7\u00e3o, comunica\u00e7\u00e3o, cultura, sociedade civil, empreendedorismo e inova\u00e7\u00e3o.<\/p>\n\n\n\n<p>O seu principal objectivo \u00e9 fortalecer a coopera\u00e7\u00e3o internacional, promover a partilha de conhecimentos e desenvolver solu\u00e7\u00f5es conjuntas para desafios globais e locais.<\/p>\n\n\n\n<p>Ao integrar esta comunidade, os membros t\u00eam acesso a oportunidades de networking, f\u00f3runs de di\u00e1logo, programas de forma\u00e7\u00e3o cont\u00ednua e iniciativas colaborativas que visam o refor\u00e7o da lideran\u00e7a e o impacto social positivo nos seus pa\u00edses de origem.<\/p>\n\n\n\n<p>&#8220;Este diploma n\u00e3o \u00e9 o fim, mas o in\u00edcio de uma caminhada que auguro ser agora muito mais produtiva, em prol da cultura do meu pa\u00eds&#8221;, escreveu Patr\u00edcia Faria.<\/p>\n\n\n\n<p>A artista angolana mostrou-se profundamente agradecida ao Governo Norte-Americano e tamb\u00e9m pela Embaixada dos Estados Unidos da Am\u00e9rica.<\/p>\n\n\n\n<p>&#8220;Pelo acolhimento e reconhecimento do meu trabalho em prol da cultura do meu pa\u00eds e o papel que tenho enquanto defensora da matriz e identidade cultural&#8221;, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A artista e advogada angolana Patr\u00edcia Faria integrou recentemente a comunidade International Visitor Leadership Program (IVLP), uma iniciativa de interc\u00e2mbio profissional promovida pelo Departamento de Estado dos Estados Unidos da [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":10060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-10059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=10059"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10059\/revisions"}],"predecessor-version":[{"id":10065,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10059\/revisions\/10065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/10060"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=10059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=10059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=10059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}