{"id":10188,"date":"2026-01-23T14:04:00","date_gmt":"2026-01-23T14:04:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=10188"},"modified":"2026-01-23T12:51:23","modified_gmt":"2026-01-23T12:51:23","slug":"jesus-esta-de-olho-na-raposa-dentro-do-galinheiro","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2026\/01\/23\/jesus-esta-de-olho-na-raposa-dentro-do-galinheiro\/","title":{"rendered":"Jesus Est\u00e1 de Olho na Raposa Dentro do Galinheiro"},"content":{"rendered":"\n<p>\u00c9 recorrente o abuso sexual a menores de idade nos \u00faltimos tempos. Caso aterrorizantes de marmanjos, que se aproveitam da inoc\u00eancia e fragilidade das crian\u00e7as, para satisfazerem os desejos carnais. E muitos desses mesmos casos, infelizmente nao conhecem a mao pesada das autoridades e da justi\u00e7a, ganham corpo e vez nesta sociedade moribunda. <\/p>\n\n\n\n<p>Alias, o dreda que supostamente abusou de varias formas a jovem Belma, dizem ser efectivo da milicia, uma pessoa que podia oferecer proteccao e conforto, foi o mesmo que implantou o terror na vida de uma indefesa, naquele momento.<\/p>\n\n\n\n<p>Jesus tem visto casos em que as cenas dao-se no seio familiar e ou com a visian\u00e7a, aonde o lobo mau, mistura-se com as ovelhas, faz-se passar por avozinha na inten\u00e7ao de devorar a capuchino vermelho.<\/p>\n\n\n\n<p>O caso que recentemente chocou a todos, foi o do \u201cngombide\u201d que aproveitou-se do neg\u00f3cio da dama dele, que cuidava dos nen\u00eas alheios, para ajudar a colocar o mata-bicho na mesa do casal. O individuo, na sua astucia e com o comportamento de uma raposa, que por discuido do responsavel pelas galinhas, penetrou no galinheiro e devou a seu belo prazer. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"319\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2026\/01\/unnamed.webp\" alt=\"\" class=\"wp-image-10189\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2026\/01\/unnamed.webp 512w, https:\/\/zango.co.ao\/wp-content\/uploads\/2026\/01\/unnamed-300x187.webp 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p>O \u201cngombide\u201d, fingiu ajudar nos cuidados que a sua dama dava \u00e0s criancinhas, enquanto calculava e escolhia friamente as sua presas indefesas, uma atitude de um verdadeiro psicopata.<\/p>\n\n\n\n<p>Um alerta aos pais e encarregados, a prestarem mais aten\u00e7\u00e3o aos sinais, criancas ficam onde s\u00e3o bem tratadas e se sentem bem. Nem toda a manisfesta\u00e7\u00e3o de uma crian\u00e7a, que nega estar num determinado lugar e com determinadas pessoas, \u00e9 mera rebeldia. Crian\u00e7a brinca com crian\u00e7a. <\/p>\n\n\n\n<p>Muitos predadores v\u00eam disfarsados de avozinha, s\u00f3 para poderem devorar a capuchinho vermelho, d\u00e3o uma de \u201cbom mo\u00e7o\u201d, o tio mais amigo e antenciso com os sobrinhos, o vizinho que gosta bue Jesus est\u00e1 lembrado de um caso em que a raposa vivia no galinheiro, aproveitava a ausencia dos pais para abusar da crian\u00e7a e sob amea\u00e7a de morte. <\/p>\n\n\n\n<p>Esses ngombides t\u00eam no\u00e7\u00e3o da crucuteca e que se metem, por isso usam recursos de formas a silenciarem as vitimas, assim como o papoite de 62 anos de idade que abusava da sobrinha da esposa, com recurso a arma de fogo apontada a sua vitima. Outros dao kumbu para guloseimas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"289\" height=\"174\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2026\/01\/images-1.jpg\" alt=\"\" class=\"wp-image-10190\" style=\"width:429px;height:auto\"\/><\/figure>\n\n\n\n<p>Uma pessoa na sua s\u00e3 consci\u00eancia, n\u00e3o faria isso, mesmo que a dama j\u00e1 n\u00e3o lhe servia na cama. O que indica que pode estar envolvido em caminhos obscuros, onde um dos meios de sacrif\u00edcio \u00e9 ngombelar as pessoas.<\/p>\n\n\n\n<p>Falta a m\u00e3o pesada daqueles tios do Plen\u00e1rio, que aprovam mambos que &#8220;fatigam&#8221; os demais. Podiam ainda aprovar uma lei do retorno, porque o karma demora, ent\u00e3o seria P\u00e3o p\u00e3o, queijo queijo; Quem viola, \u00e9 violado. Quem rouba, \u00e9 roubado e quem mata, \u00e9 \u201cmatado\u201d\u2026 Resumindo, ac\u00e7\u00f5es desagrad\u00e1veis, chocantes e aterrorizadoras, a reac\u00e7\u00e3o seria uma viagem sem regresso, ao indiv\u00edduo protagonista.<\/p>\n\n\n\n<p>Nas bandas de alguns povos duros em assuntos do g\u00e9nero, est\u00e3o a avan\u00e7ar para uma postura mais rigorosa contra crimes sexuais violentos, com parlamentares impulsionando uma proposta que permitiria a castra\u00e7\u00e3o qu\u00edmica para estupradores e ped\u00f3filos condenados. Noutras bandas, sao capturados e executados letalmente, passando assim a mensagem a outros teimosos\u2026 teimoso sofre! <\/p>\n\n\n\n<p><strong>Jesus Est\u00e1 De Olho!!!<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 recorrente o abuso sexual a menores de idade nos \u00faltimos tempos. Caso aterrorizantes de marmanjos, que se aproveitam da inoc\u00eancia e fragilidade das crian\u00e7as, para satisfazerem os desejos carnais. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":4248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[636],"tags":[],"class_list":["post-10188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniao"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=10188"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10188\/revisions"}],"predecessor-version":[{"id":10191,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10188\/revisions\/10191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/4248"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=10188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=10188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=10188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}