{"id":10389,"date":"2026-02-09T13:07:28","date_gmt":"2026-02-09T13:07:28","guid":{"rendered":"https:\/\/zango.co.ao\/?p=10389"},"modified":"2026-02-09T13:07:30","modified_gmt":"2026-02-09T13:07:30","slug":"angolanos-integram-jurados-do-festival-de-video-no-brasil","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2026\/02\/09\/angolanos-integram-jurados-do-festival-de-video-no-brasil\/","title":{"rendered":"Angolanos integram jurados do Festival de Video no Brasil"},"content":{"rendered":"\n<p>Os profissionais angolanos Alberto Charamba e Krisnano Santos foram selecionados para integrar o corpo de jurados da 36.\u00aa edi\u00e7\u00e3o do FestVideo 2026, um dos festivais mais prestigiados do Brasil.<\/p>\n\n\n\n<p>A actividade, agendada para 29 de abril, em S\u00e3o Paulo, \u00e9 realizada desde 1990 pela APCM (Associa\u00e7\u00e3o de Profissionais de Comunica\u00e7\u00e3o e Marketing) e destaca-se por valorizar a excel\u00eancia t\u00e9cnica no audiovisual e na comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Alberto Charamba \u00e9 um criativo angolano com mais de dez anos de experi\u00eancia nas \u00e1reas de design, marketing e comunica\u00e7\u00e3o. J\u00e1 Krisnano Santos, conhecido profissionalmente como Kris, \u00e9 realizador, produtor e director criativo da Free Dation.<\/p>\n\n\n\n<p>No FestVideo, considerado um dos mais importantes festivais publicit\u00e1rios do Brasil, os dois criativos angolanos v\u00e3o integrar o painel ao lado de outros profissionais renomados do sector criativo brasileiro e internacional.<\/p>\n\n\n\n<p>Importa referir que o FestVideo integra o calend\u00e1rio oficial de eventos do estado de S\u00e3o Paulo e \u00e9 reconhecido como um dos pr\u00e9mios mais respeitados da publicidade brasileira.H\u00e1 cinco anos, o festival criou ainda a categoria Filme Capital, destinada a ag\u00eancias sediadas nas capitais brasileiras.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os profissionais angolanos Alberto Charamba e Krisnano Santos foram selecionados para integrar o corpo de jurados da 36.\u00aa edi\u00e7\u00e3o do FestVideo 2026, um dos festivais mais prestigiados do Brasil. A [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":10391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-10389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=10389"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10389\/revisions"}],"predecessor-version":[{"id":10390,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10389\/revisions\/10390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/10391"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=10389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=10389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=10389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}