{"id":10948,"date":"2026-03-19T11:18:54","date_gmt":"2026-03-19T11:18:54","guid":{"rendered":"https:\/\/zango.co.ao\/?p=10948"},"modified":"2026-03-19T11:18:57","modified_gmt":"2026-03-19T11:18:57","slug":"ex-diplomata-belga-sera-julgado-pela-morte-de-patrice-lumumba","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2026\/03\/19\/ex-diplomata-belga-sera-julgado-pela-morte-de-patrice-lumumba\/","title":{"rendered":"Ex-diplomata belga ser\u00e1 julgado pela morte de Patrice Lumumba"},"content":{"rendered":"\n<p>Um tribunal da B\u00e9lgica decidiu levar a julgamento o ex-diplomata \u00c9tienne Davignon, de 93 anos, no \u00e2mbito do assassinato de Patrice Lumumba, primeiro-ministro da Rep\u00fablica Democr\u00e1tica do Congo e uma das figuras mais emblem\u00e1ticas do pan-africanismo.\u200e\u200e<\/p>\n\n\n\n<p>A decis\u00e3o judicial, considerada hist\u00f3rica, foi saudada pela fam\u00edlia de Lumumba como um passo importante na busca por justi\u00e7a, mais de seis d\u00e9cadas ap\u00f3s o crime. <\/p>\n\n\n\n<p>Davignon torna-se assim o primeiro respons\u00e1vel belga a enfrentar julgamento no caso.\u200e\u200ePatrice Lumumba foi assassinado em 1961, poucos meses ap\u00f3s conduzir o pa\u00eds \u00e0 independ\u00eancia. <\/p>\n\n\n\n<p>Executado por um pelot\u00e3o de fuzilamento na regi\u00e3o de Katanga, o seu corpo foi posteriormente dissolvido em \u00e1cido numa tentativa de eliminar provas. Durante d\u00e9cadas, nenhum respons\u00e1vel foi condenado.\u200e Apenas em 2022, um dente, o \u00fanico vest\u00edgio conhecido do l\u00edder, foi recuperado e devolvido \u00e0 fam\u00edlia.\u200e<\/p>\n\n\n\n<p>Segundo investiga\u00e7\u00f5es hist\u00f3ricas, o assassinato ocorreu no contexto da Guerra Fria e envolveu interesses internacionais. <\/p>\n\n\n\n<p>Relat\u00f3rios apontam que a CIA ter\u00e1 participado em planos para eliminar Lumumba, enquanto for\u00e7as congolesas, com apoio da B\u00e9lgica, executaram a opera\u00e7\u00e3o.\u200e\u200eO tribunal belga decidiu avan\u00e7ar com o julgamento, apesar dos argumentos da defesa de Davignon, que alegou o longo tempo decorrido desde os acontecimentos. <\/p>\n\n\n\n<p>Os promotores acusam o antigo diplomata de participa\u00e7\u00e3o em crimes de guerra, incluindo o seu alegado papel na deten\u00e7\u00e3o e transfer\u00eancia ilegal de Lumumba, bem como no tratamento degradante a que foi submetido.<\/p>\n\n\n\n<p>\u200e\u200eA decis\u00e3o tamb\u00e9m abrange os assassinatos de aliados pol\u00edticos de Lumumba, como Maurice Mpolo e Joseph Okito, mortos no mesmo contexto.\u200e\u200eA fam\u00edlia do antigo l\u00edder congol\u00eas considera o processo uma vit\u00f3ria significativa. Para os seus representantes legais, trata-se de um momento crucial para confrontar o passado colonial e responsabilizar actores pol\u00edticos europeus envolvidos em crimes hist\u00f3ricos em \u00c1frica.\u200e\u200e<\/p>\n\n\n\n<p>O caso reacende o debate internacional sobre justi\u00e7a hist\u00f3rica, mem\u00f3ria colonial e a responsabiliza\u00e7\u00e3o de figuras que desempenharam pap\u00e9is decisivos em epis\u00f3dios marcantes da hist\u00f3ria africana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um tribunal da B\u00e9lgica decidiu levar a julgamento o ex-diplomata \u00c9tienne Davignon, de 93 anos, no \u00e2mbito do assassinato de Patrice Lumumba, primeiro-ministro da Rep\u00fablica Democr\u00e1tica do Congo e uma [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":10949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[632],"tags":[],"class_list":["post-10948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=10948"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10948\/revisions"}],"predecessor-version":[{"id":10950,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/10948\/revisions\/10950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/10949"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=10948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=10948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=10948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}