{"id":1136,"date":"2024-06-27T07:35:46","date_gmt":"2024-06-27T07:35:46","guid":{"rendered":"https:\/\/zango.co.ao\/?p=1136"},"modified":"2024-06-27T07:35:46","modified_gmt":"2024-06-27T07:35:46","slug":"presidente-do-quenia-rejeita-todas-as-clausulasdo-projecto-de-lei-de-financas-de-2024","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2024\/06\/27\/presidente-do-quenia-rejeita-todas-as-clausulasdo-projecto-de-lei-de-financas-de-2024\/","title":{"rendered":"Presidente do Qu\u00e9nia rejeita \u201ctodas as cl\u00e1usulas\u201ddo Projecto de Lei de Finan\u00e7as de 2024"},"content":{"rendered":"\n<p>O presidente do Qu\u00e9nia, William Ruto, rejeitou &#8220;todas as cl\u00e1usulas&#8221; do controverso projeto de lei de finan\u00e7as de 2024 que desencadeou protestos mortais no pa\u00eds do Leste Africano na semana passada e no in\u00edcio desta semana.<\/p>\n\n\n\n<p>Desde ent\u00e3o, Ruto apresentou oficialmente ao parlamento do Qu\u00e9nia a sua decis\u00e3o de recusar o projecto de lei na sua totalidade.<\/p>\n\n\n\n<p>&#8220;No exerc\u00edcio dos poderes que me s\u00e3o conferidos pela constitui\u00e7\u00e3o (do Qu\u00e9nia), e tendo reservas sobre o conte\u00fado do projeto de lei na sua totalidade, recuso-me a dar parecer favor\u00e1vel ao Projeto de Lei das Finan\u00e7as de 2024, e encaminho o projeto de lei para reconsidera\u00e7\u00e3o pela Assembleia Nacional com a recomenda\u00e7\u00e3o de elimina\u00e7\u00e3o de todas as suas cl\u00e1usulas&#8221;, disse Ruto em memorando de encaminhamento presidencial na quarta-feira.<\/p>\n\n\n\n<p>Ruto disse que levou em considera\u00e7\u00e3o a \u201cexpress\u00e3o generalizada de insatisfa\u00e7\u00e3o por parte do p\u00fablico sobre o conte\u00fado do Projeto de Lei de Finan\u00e7as 2024\u201d.<\/p>\n\n\n\n<p>Entretanto, Os manifestantes quenianos prepararam-se para retomar os protestos na quinta-feira, um dia depois de o presidente William Ruto ter feito uma reviravolta dram\u00e1tica e retirado os pol\u00eamicos aumentos de impostos ap\u00f3s com\u00edcios mortais no in\u00edcio da semana<\/p>\n\n\n\n<p>Apesar de o presidente William Ruto ter feito uma reviravolta dram\u00e1tica e retirado os pol\u00eamicos aumentos de impostos, os manifestantes quenianos prepararam-se para retomar os protestos esta quinta-feira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alguns manifestantes comprometeram-se a prosseguir com as manifesta\u00e7\u00f5es, e agora exigem a demiss\u00e3o do presidente.<\/p>\n","protected":false},"author":8,"featured_media":1141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[322,268,176,266],"class_list":["post-1136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","tag-impostos","tag-protesto","tag-quenia","tag-william-ruto"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=1136"}],"version-history":[{"count":4,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1136\/revisions"}],"predecessor-version":[{"id":1140,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1136\/revisions\/1140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/1141"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=1136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=1136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=1136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}