{"id":1224,"date":"2024-07-01T11:41:57","date_gmt":"2024-07-01T11:41:57","guid":{"rendered":"https:\/\/zango.co.ao\/?p=1224"},"modified":"2024-07-18T19:24:32","modified_gmt":"2024-07-18T19:24:32","slug":"familia-biden-pede-que-presidente-continue-na-corrida-eleitoral-apesar-do-knockout-no-debate-com-trump","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2024\/07\/01\/familia-biden-pede-que-presidente-continue-na-corrida-eleitoral-apesar-do-knockout-no-debate-com-trump\/","title":{"rendered":"Fam\u00edlia Biden pede que presidente continue na corrida eleitoral, apesar do \u201cKnockout\u201d no debate com Trump"},"content":{"rendered":"\n<p>A fam\u00edlia do presidente Joe Biden aproveitou uma reuni\u00e3o de domingo em Camp David para inst\u00e1-lo a permanecer na corrida e continuar lutando, apesar de seu p\u00e9ssimo desempenho no debate com Donald Trump, e alguns membros criticaram como sua equipa o preparou para o confronto, de acordo com quatro pessoas familiarizado com as discuss\u00f5es.<br>Biden passou o domingo com a primeira-dama Jill Biden , seus filhos e netos.<br>Foi uma viagem previamente agendada ao retiro presidencial em Maryland para uma sess\u00e3o de fotos com Annie Leibovitz para a pr\u00f3xima Conven\u00e7\u00e3o Nacional Democrata.<br>Mas a reuni\u00e3o foi tamb\u00e9m um exerc\u00edcio para tentar descobrir como acalmar a ansiedade democrata que explodiu ap\u00f3s o desempenho de quinta-feira.<br>Embora sua fam\u00edlia estivesse ciente de qu\u00e3o mal ele se saiu contra Donald Trump, eles tamb\u00e9m continuam a pensar que ele \u00e9 a melhor pessoa para derrotar o prov\u00e1vel candidato republicano.<br>A fam\u00edlia Biden tamb\u00e9m acredita que ele \u00e9 capaz de fazer o trabalho de presidente por mais quatro anos, de acordo com as pessoas que n\u00e3o estavam autorizadas a falar publicamente sobre discuss\u00f5es internas e falaram com a Associated Press sob condi\u00e7\u00e3o de anonimato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cresce um sentimento de preocupa\u00e7\u00e3o dentro dos altos escal\u00f5es do Partido Democrata de que os l\u00edderes da campanha de Joe Biden e do Comit\u00ea Nacional Democrata n\u00e3o est\u00e3o levar a s\u00e9rio o suficiente o impacto do desempenho do presidente no debate.<\/p>\n","protected":false},"author":8,"featured_media":1229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[343],"tags":[],"class_list":["post-1224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=1224"}],"version-history":[{"count":4,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1224\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1224\/revisions\/1230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/1229"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=1224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=1224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}