{"id":1955,"date":"2024-08-15T10:04:22","date_gmt":"2024-08-15T10:04:22","guid":{"rendered":"https:\/\/zango.co.ao\/?p=1955"},"modified":"2024-08-15T10:08:03","modified_gmt":"2024-08-15T10:08:03","slug":"queimadas-anarquicas-ameacam-vidas-e-biodiversidade-em-angola","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2024\/08\/15\/queimadas-anarquicas-ameacam-vidas-e-biodiversidade-em-angola\/","title":{"rendered":"Queimadas An\u00e1rquicas Amea\u00e7am Vidas e Biodiversidade em Angola"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Campanhas de sensibiliza\u00e7\u00e3o s\u00e3o intensificadas para conter danos ambientais e humanos.<\/h3>\n\n\n\n<p>Nos \u00faltimos meses, Angola tem enfrentado uma grave crise ambiental provocada pelas queimadas an\u00e1rquicas, que j\u00e1 resultaram em 22 mortes e na destrui\u00e7\u00e3o de mais de 10 mil hectares de terra. Essas queimadas, frequentemente iniciadas para preparar terrenos agr\u00edcolas ou facilitar a ca\u00e7a furtiva, t\u00eam causado perdas significativas n\u00e3o apenas para a agricultura, mas tamb\u00e9m para a biodiversidade local, afetando esp\u00e9cies de animais e plantas.<\/p>\n\n\n\n<p>As autoridades enfrentam grandes desafios na conten\u00e7\u00e3o desses inc\u00eandios devido \u00e0 falta de recursos adequados. Esfor\u00e7os est\u00e3o sendo feitos para educar as comunidades rurais sobre os perigos das queimadas descontroladas e implementar planos de conting\u00eancia para mitigar os danos. Contudo, identificar e responsabilizar os autores desses inc\u00eandios continua sendo uma tarefa dif\u00edcil.<\/p>\n\n\n\n<p>\u00c9 imperativo que as campanhas de sensibiliza\u00e7\u00e3o e as medidas de preven\u00e7\u00e3o sejam refor\u00e7adas para evitar mais perdas humanas e ambientais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campanhas de sensibiliza\u00e7\u00e3o s\u00e3o intensificadas para conter danos ambientais e humanos. Nos \u00faltimos meses, Angola tem enfrentado uma grave crise ambiental provocada pelas queimadas an\u00e1rquicas, que j\u00e1 resultaram em 22 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[632],"tags":[],"class_list":["post-1955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=1955"}],"version-history":[{"count":3,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1955\/revisions"}],"predecessor-version":[{"id":1959,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/1955\/revisions\/1959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/1956"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=1955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=1955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=1955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}