{"id":2127,"date":"2024-10-14T13:34:56","date_gmt":"2024-10-14T13:34:56","guid":{"rendered":"https:\/\/zango.co.ao\/?p=2127"},"modified":"2024-10-14T14:11:06","modified_gmt":"2024-10-14T14:11:06","slug":"inac-regista-perto-de-400-deduncias-de-violencia-contra-crianca-em-uma-semana","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2024\/10\/14\/inac-regista-perto-de-400-deduncias-de-violencia-contra-crianca-em-uma-semana\/","title":{"rendered":"INAC REGISTA PERTO DE 400 DEN\u00daNCIAS DE VIOL\u00caNCIA CONTRA CRIAN\u00c7A EM UMA SEMANA"},"content":{"rendered":"\n<p>Por: Reda\u00e7\u00e3o Portal Zango<\/p>\n\n\n\n<p>O Instituto Nacional da Crian\u00e7a, INAC, atrav\u00e9s da sua linha de atendimento S.O.S Crian\u00e7a, no n\u00famero 15015, rececionou um total de 393 den\u00fancias de viol\u00eancia contra crian\u00e7a registadas em todo pa\u00eds, com destaque para as prov\u00edncias de Luanda, Bi\u00e9, Benguela, Huambo, Lunda-sul Malanje e Namibe.<\/p>\n\n\n\n<p>Os dados foram apresentados pela porta-voz do INAC, Rosalina Domingos, durante a apresenta\u00e7\u00e3o do balan\u00e7o das ocorr\u00eancias registadas no per\u00edodo de 6 a 12&nbsp; de Outubro, onde avan\u00e7ou o registo de 153 den\u00fancias de fuga a paternidade e disputa de guarda, 69 de trabalho infantil, 58 de viol\u00eancia f\u00edsica e psicol\u00f3gica, 16 de abuso sexual, e outras.<\/p>\n\n\n\n<p>Na prov\u00edncia de Luanda, Rosalina Domingos reportou 5 den\u00fancias registadas nos munic\u00edpios de Luanda, Viana, Belas e Cazenga, sendo 4 de abuso sexual, cuja as v\u00edtimas t\u00eam entre os 7 e 17 anos de idade, e uma outra den\u00fancia envolvendo 4 crian\u00e7as com idades compreendidas entre os 9 e 15 anos de idade, que s\u00e3o acusadas de feiticeiras pelo pr\u00f3prio pai e pelo tio, sendo brutalmente agredidas pelos dois homens que usam paus, mangueiras e algumas vezes lan\u00e7am-lhes gasolina.<\/p>\n\n\n\n<p>Desde o m\u00eas de Agosto, o Instituto Nacional da Crian\u00e7a tem registado diversas den\u00fancias que se fixam nesta ordem num\u00e9rica, 400 den\u00fancias, o que demonstra um risco para as crian\u00e7as que sofrem diversos abusos praticados por quem devia proteg\u00e9-las.<\/p>\n\n\n\n<p>Fonte: INAC<\/p>\n\n\n\n<p>Imagem: Internet<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Reda\u00e7\u00e3o Portal Zango O Instituto Nacional da Crian\u00e7a, INAC, atrav\u00e9s da sua linha de atendimento S.O.S Crian\u00e7a, no n\u00famero 15015, rececionou um total de 393 den\u00fancias de viol\u00eancia contra [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[632],"tags":[],"class_list":["post-2127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/2127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=2127"}],"version-history":[{"count":6,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/2127\/revisions"}],"predecessor-version":[{"id":2168,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/2127\/revisions\/2168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/2128"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=2127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=2127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=2127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}