{"id":3024,"date":"2025-02-12T17:40:00","date_gmt":"2025-02-12T17:40:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=3024"},"modified":"2025-02-12T17:42:48","modified_gmt":"2025-02-12T17:42:48","slug":"donald-trump-suspende-lei-anticorrupcao-que-proibe-suborno-no-exterior","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/02\/12\/donald-trump-suspende-lei-anticorrupcao-que-proibe-suborno-no-exterior\/","title":{"rendered":"Donald Trump Suspende Lei Anticorrup\u00e7\u00e3o que Pro\u00edbe Suborno no Exterior"},"content":{"rendered":"\n<p>O presidente dos Estados Unidos, Donald Trump, assinou na segunda-feira, 10 de Fevereiro, um decreto orientando o Departamento de Justi\u00e7a a suspender os processos contra norte-americanos acusados de subornar funcion\u00e1rios de governos estrangeiros ao tentar ganhar ou manter neg\u00f3cios nesses pa\u00edses.<\/p>\n\n\n\n<p>&#8220;Isso vai significar muito mais neg\u00f3cios para os Estados Unidos&#8221;, disse Trump aos rep\u00f3rteres ao assinar o decreto no Sal\u00e3o Oval na segunda-feira.<\/p>\n\n\n\n<p>Segundo a Reuters, o decreto de Trump suspende a aplica\u00e7\u00e3o da Lei de Pr\u00e1ticas de Corrup\u00e7\u00e3o no Exterior (FCPA), que tem quase meio s\u00e9culo de exist\u00eancia, e instrui a procuradora-geral, Pam Bondi, a analisar as ac\u00e7\u00f5es actuais e passadas relacionadas \u00e0 lei e preparar novas directrizes para a aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p>A lei, promulgada em 1977, pro\u00edbe as empresas que operam nos Estados Unidos de subornar autoridades estrangeiras. Com o passar do tempo, ela se tornou uma for\u00e7a orientadora de como as empresas norte-americanas operam no exterior.<\/p>\n\n\n\n<p>A organiza\u00e7\u00e3o de vigil\u00e2ncia anticorrup\u00e7\u00e3o Transpar\u00eancia Internacional disse que a FCPA fez dos Estados Unidos um l\u00edder no combate \u00e0 corrup\u00e7\u00e3o global.<\/p>\n\n\n\n<p>O decreto de Trump \u201cdiminui \u2013 e pode abrir caminho para a elimina\u00e7\u00e3o completa \u2013 da joia da coroa na luta dos EUA contra a corrup\u00e7\u00e3o global\u201d, disse em comunicado, Gary Kalman, director executivo da Transpar\u00eancia Internacional dos EUA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente dos Estados Unidos, Donald Trump, assinou na segunda-feira, 10 de Fevereiro, um decreto orientando o Departamento de Justi\u00e7a a suspender os processos contra norte-americanos acusados de subornar funcion\u00e1rios [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[343],"tags":[],"class_list":["post-3024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=3024"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3024\/revisions"}],"predecessor-version":[{"id":3025,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3024\/revisions\/3025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/3026"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=3024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=3024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=3024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}