{"id":3271,"date":"2025-02-22T11:01:01","date_gmt":"2025-02-22T11:01:01","guid":{"rendered":"https:\/\/zango.co.ao\/?p=3271"},"modified":"2025-02-22T11:01:03","modified_gmt":"2025-02-22T11:01:03","slug":"programa-de-fomento-ao-emprego-do-pnud-vai-abranger-jovens-angolanos","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/02\/22\/programa-de-fomento-ao-emprego-do-pnud-vai-abranger-jovens-angolanos\/","title":{"rendered":"Programa de Fomento ao Emprego do PNUD vai Abranger Jovens Angolanos"},"content":{"rendered":"\n<p>Angola vai beneficiar, em breve, de um projecto para impulsionar o fomento de oportunidades de emprego para os jovens, com foco nas \u00e1reas da tecnologia de informa\u00e7\u00e3o, finan\u00e7as e da agricultura, no quadro do Programa Global do PNUD.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o foi avan\u00e7ada pela administradora-adjunta do Programa das Na\u00e7\u00f5es Unidas para o Desenvolvimento (PNUD), Ahunna Eziakonwa, no fim de uma audi\u00eancia que lhe foi concedida pelo Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, como noticiou o Jornal de Angola, nesta quinta-feira (20).<\/p>\n\n\n\n<p>Ahunna Eziakonwa disse que Angola se vai tornar no d\u00e9cimo primtpa\u00eds do continente a contar com este Hub da Agri-tecnologia, enquadrado no Programa Global, lan\u00e7ado no ano passado em Davos, Su\u00ed\u00e7a.<\/p>\n\n\n\n<p>A Agri-tecnologia, explicou a respons\u00e1vel, vai abarcar as \u00e1reas das tecnologias de informa\u00e7\u00e3o, criando uma cadeia de valores, \u201cpor ser aqui onde emergem mais empregos e possibilidades econ\u00f3micas para a juventude\u201d.<\/p>\n\n\n\n<p>Segundo a tamb\u00e9m secret\u00e1ria-geral adjunta da ONU, o Programa designado Timbuktoo-PNUD, est\u00e1 or\u00e7ado em mil milh\u00f5es de d\u00f3lares, visa tamb\u00e9m desenvolver as \u00e1reas das tecnologias, com realce para os sectores da Sa\u00fade, Agricultura e Tecnologia Financeira.<\/p>\n\n\n\n<p>&#8220;N\u00f3s vamos trabalhar com o Governo de Angola, bastando apenas que se disponibilize um espa\u00e7o para alojar o projecto, com a garantia de trabalharmos juntos na mobiliza\u00e7\u00e3o de equipamentos\u201d, ressaltou.<\/p>\n\n\n\n<p>\u201cNa verdade, trata-se de algo como se fosse um laborat\u00f3rio, onde podemos realizar experimentos, prototipagem e incuba\u00e7\u00e3o, e a partir da\u00ed buscar as ideias em desenvolvimento na agricultura\u201d, explicou.<\/p>\n\n\n\n<p>Ao reagir \u00e0 quest\u00e3o de como Angola pode contar com o PNUD para fortalecer as oportunidades de empregos para os jovens, Ahunna Eziakonwa acrescentou que, atrav\u00e9s destes passos, a juventude vai ser incentivada a empreendeder, envolvendo o sector privado, permitindo, com isso, a cria\u00e7\u00e3o de mais empresas e mais neg\u00f3cios, que podem ir para al\u00e9m de Angola.<\/p>\n\n\n\n<p>Os hubs do Timbuktoo s\u00e3o centros de excel\u00eancia em \u00c1frica, apoiados pelo PNUD, que visam impulsionar a inova\u00e7\u00e3o e o desenvolvimento econ\u00f3mico.<\/p>\n\n\n\n<p>Ahunna Eziakonwa disse ter aproveitado, tamb\u00e9m, o encontro para felicitar o Chefe de Estado angolano pela recente elei\u00e7\u00e3o ao cargo de Presidente da Uni\u00e3o Africana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angola vai beneficiar, em breve, de um projecto para impulsionar o fomento de oportunidades de emprego para os jovens, com foco nas \u00e1reas da tecnologia de informa\u00e7\u00e3o, finan\u00e7as e da [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[650],"tags":[],"class_list":["post-3271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sustentabilidade"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=3271"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3271\/revisions"}],"predecessor-version":[{"id":3272,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/3271\/revisions\/3272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/3273"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=3271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=3271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=3271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}