{"id":4100,"date":"2025-04-01T07:28:37","date_gmt":"2025-04-01T07:28:37","guid":{"rendered":"https:\/\/zango.co.ao\/?p=4100"},"modified":"2025-04-01T07:28:39","modified_gmt":"2025-04-01T07:28:39","slug":"cientistas-do-kaist-descobriram-como-acabar-com-o-cancer","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/04\/01\/cientistas-do-kaist-descobriram-como-acabar-com-o-cancer\/","title":{"rendered":"Cientistas do KAIST descobriram como Acabar com o C\u00e2ncer"},"content":{"rendered":"\n<p>Apesar do desenvolvimento de in\u00fameras tecnologias de tratamento de c\u00e2ncer, o objectivo comum das terapias actuais de c\u00e2ncer \u00e9 eliminar c\u00e9lulas cancer\u00edgenas. <\/p>\n\n\n\n<p>Essa abordagem, no entanto, enfrenta limita\u00e7\u00f5es fundamentais, incluindo c\u00e9lulas cancer\u00edgenas desenvolvendo resist\u00eancia e retornando, bem como efeitos colaterais severos da destrui\u00e7\u00e3o de c\u00e9lulas saud\u00e1veis.<\/p>\n\n\n\n<p>O KAIST (representado pelo presidente Kwang Hyung Lee) anunciou no dia 20 de Dezembro que uma equipa de pesquisa liderada pelo professor Kwang-Hyun Cho do Departamento de Engenharia Biol\u00f3gica e Cerebral desenvolveu uma tecnologia inovadora que pode tratar o c\u00e2ncer de c\u00f3lon convertendo c\u00e9lulas cancer\u00edgenas em um estado semelhante \u00e0s c\u00e9lulas normais do c\u00f3lon sem mat\u00e1-las, evitando assim efeitos colaterais.<\/p>\n\n\n\n<p>A equipa de pesquisa se concentrou na observa\u00e7\u00e3o de que, durante o processo de oncog\u00eanese, as c\u00e9lulas normais regridem ao longo de sua traject\u00f3ria de diferencia\u00e7\u00e3o.<\/p>\n\n\n\n<p>Com base nessa percep\u00e7\u00e3o, eles desenvolveram uma tecnologia para criar um g\u00eameo digital da rede de genes associada \u00e0 traject\u00f3ria de diferencia\u00e7\u00e3o de c\u00e9lulas normais.<\/p>\n\n\n\n<p>Esta pesquisa demonstra que a revers\u00e3o de c\u00e9lulas cancer\u00edgenas pode ser sistematicamente alcan\u00e7ada pela an\u00e1lise e utiliza\u00e7\u00e3o do g\u00eameo digital da rede de genes de c\u00e9lulas cancer\u00edgenas, em vez de depender de descobertas fortuitas.<\/p>\n\n\n\n<p> As descobertas s\u00e3o uma promessa significativa para o desenvolvimento de terapias revers\u00edveis contra o c\u00e2ncer que podem ser aplicadas a v\u00e1rios tipos de c\u00e2ncer.<\/p>\n\n\n\n<p>O professor Kwang-Hyun Cho observou: &#8220;O facto de que c\u00e9lulas cancer\u00edgenas podem ser convertidas de volta em c\u00e9lulas normais \u00e9 um fen\u00f4meno surpreendente. Este estudo prova que tal revers\u00e3o pode ser induzida sistematicamente.&#8221;<\/p>\n\n\n\n<p>Ele enfatizou ainda que &#8220;esta pesquisa introduz o novo conceito de terapia revers\u00edvel do c\u00e2ncer revertendo c\u00e9lulas cancer\u00edgenas para c\u00e9lulas normais.<\/p>\n\n\n\n<p> Ela tamb\u00e9m desenvolve tecnologia fundamental para identificar alvos para revers\u00e3o do c\u00e2ncer por meio da an\u00e1lise sistem\u00e1tica de trajet\u00f3rias de diferencia\u00e7\u00e3o de c\u00e9lulas normais.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"890\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011.jpg\" alt=\"\" class=\"wp-image-4103\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011.jpg 900w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011-300x297.jpg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011-768x759.jpg 768w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011-716x708.jpg 716w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/03\/1000191011-820x811.jpg 820w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>&#8220;Esta pesquisa incluiu contribui\u00e7\u00f5es de Jeong-Ryeol Gong, Chun-Kyung Lee, Hoon-Min Kim, Juhee Kim e Jaeog Jeon, e foi publicada na edi\u00e7\u00e3o online do peri\u00f3dico internacional Advanced Science da Wiley em 11 de Dezembro de 2024. T\u00edtulo:<em><strong> \u201cControle de trajet\u00f3rias de diferencia\u00e7\u00e3o celular para revers\u00e3o do c\u00e2ncer\u201d.<\/strong><\/em><\/p>\n\n\n\n<p>O estudo foi apoiado pelo Minist\u00e9rio da Ci\u00eancia, ICT e pela <em>National Research Foundation of Korea<\/em> por meio do M<em>id-Career Researcher Program <\/em>e do <em>Basic Research Laboratory Program.<\/em><\/p>\n\n\n\n<p> As descobertas da pesquisa foram transferidas para a BioRevert Inc., onde ser\u00e3o usadas para o desenvolvimento de terapias pr\u00e1ticas de revers\u00e3o do c\u00e2ncer.<\/p>\n\n\n\n<p><strong>Fonte<\/strong>: KAIST news<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar do desenvolvimento de in\u00fameras tecnologias de tratamento de c\u00e2ncer, o objectivo comum das terapias actuais de c\u00e2ncer \u00e9 eliminar c\u00e9lulas cancer\u00edgenas. Essa abordagem, no entanto, enfrenta limita\u00e7\u00f5es fundamentais, incluindo [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":4102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especial"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/4100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=4100"}],"version-history":[{"count":4,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/4100\/revisions"}],"predecessor-version":[{"id":4107,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/4100\/revisions\/4107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/4102"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=4100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=4100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=4100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}