{"id":5479,"date":"2025-05-21T15:03:33","date_gmt":"2025-05-21T15:03:33","guid":{"rendered":"https:\/\/zango.co.ao\/?p=5479"},"modified":"2025-05-21T15:03:35","modified_gmt":"2025-05-21T15:03:35","slug":"pesquisador-ugandes-desenvolve-medicamento-para-cura-do-cancro-de-mama","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/05\/21\/pesquisador-ugandes-desenvolve-medicamento-para-cura-do-cancro-de-mama\/","title":{"rendered":"Pesquisador Ugand\u00eas Desenvolve Medicamento para Cura do Cancro de Mama"},"content":{"rendered":"\n<p>Emmanuel Mukisa Kiyonga, farmac\u00eautico e pesquisador ugandense, desenvolveu uma nova formula\u00e7\u00e3o de medicamento Raloxifeno Cloridrato Hidrato, medicamento com potencial para revolucionar o tratamento da osteoporose p\u00f3s-menopausa e do cancro da mama.<\/p>\n\n\n\n<p>A f\u00f3rmula inovadora desenvolvida por  Emmanuel n\u00e3o visa apenas fornecer uma op\u00e7\u00e3o de tratamento eficaz, mas tamb\u00e9m busca abordar as barreiras econ\u00f4micas que afectam o tratamento do cancro em \u00c1frica.<\/p>\n\n\n\n<p>Ao aproveitar recursos locais e colaborar com empresas farmac\u00eauticas locais, o pesquisador prev\u00ea um futuro em que os medicamentos contra o cancro ser\u00e3o produzidos internamente, de modo a reduzir significativamente os custos e melhorar a disponibilidade.<\/p>\n\n\n\n<p>Durante seu per\u00edodo na Universidade de Ci\u00eancias da Sa\u00fade Sefako Makgatho (SMU), na \u00c1frica do Sul, se tornou o primeiro estudante na hist\u00f3ria da universidade a obter uma patente farmac\u00eautica.<\/p>\n\n\n\n<p>A descoberta inovadora de Kiyonga n\u00e3o apenas melhora a biodisponibilidade do medicamento, mas tamb\u00e9m o torna mais econ\u00f4mico e acess\u00edvel, especialmente para comunidades de baixa renda.<\/p>\n\n\n\n<p>Seu trabalho j\u00e1 est\u00e1 repercutir no espa\u00e7o global da pesquisa farmac\u00eautica, oferecendo esperan\u00e7a renovada a milh\u00f5es de mulheres em todo o mundo.<\/p>\n\n\n\n<p>De um come\u00e7o humilde em Kampala \u00e0 conquista do Pr\u00eamio Jovem Cientista da Academia de Ci\u00eancias Farmac\u00eauticas da \u00c1frica do Sul, a jornada de Kiyonga \u00e9 um testemunho de resili\u00eancia, inova\u00e7\u00e3o e do poder da ci\u00eancia para mudar vidas.<\/p>\n\n\n\n<p>O futuro da sa\u00fade em \u00c1frica parece cada vez mais promissor. Seu trabalho exemplifica o potencial dos inovadores africanos para enfrentar desafios urgentes de sa\u00fade e melhorar a qualidade de vida de milh\u00f5es de pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emmanuel Mukisa Kiyonga, farmac\u00eautico e pesquisador ugandense, desenvolveu uma nova formula\u00e7\u00e3o de medicamento Raloxifeno Cloridrato Hidrato, medicamento com potencial para revolucionar o tratamento da osteoporose p\u00f3s-menopausa e do cancro da [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-5479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/5479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=5479"}],"version-history":[{"count":4,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/5479\/revisions"}],"predecessor-version":[{"id":5487,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/5479\/revisions\/5487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/5480"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=5479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=5479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=5479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}