{"id":6193,"date":"2025-06-20T15:05:00","date_gmt":"2025-06-20T15:05:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=6193"},"modified":"2025-06-20T14:48:48","modified_gmt":"2025-06-20T14:48:48","slug":"rdc-e-rwanda-aprovam-acordo-de-paz-a-assinar-em-washington","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/06\/20\/rdc-e-rwanda-aprovam-acordo-de-paz-a-assinar-em-washington\/","title":{"rendered":"RDC e Rwanda Aprovam Acordo de Paz a Assinar em Washington"},"content":{"rendered":"\n<p>A Rep\u00fablica Democr\u00e1tica do Congo e o Ruanda v\u00e3o assinar um acordo de paz a 27 de Junho, segundo uma declara\u00e7\u00e3o conjunta com o Departamento de Estado dos EUA.<\/p>\n\n\n\n<p>Um acordo provis\u00f3rio, anunciado pelos dois pa\u00edses e pelo Departamento de Estado dos EUA, abrange quest\u00f5es como o desarmamento, a integra\u00e7\u00e3o de grupos armados n\u00e3o estatais e o regresso dos refugiados e das pessoas deslocadas internamente no leste da RDC.<\/p>\n\n\n\n<p>O leste da RDC tem sido assolado por conflitos h\u00e1 d\u00e9cadas, com grupos armados a competir pelo acesso a recursos naturais, incluindo t\u00e2ntalo, ouro, cobalto, cobre e l\u00edtio.<\/p>\n\n\n\n<p>O Congo acusou o seu vizinho Ruanda de apoiar um dos maiores grupos da regi\u00e3o, os rebeldes M23. Segundo peritos da ONU, os rebeldes s\u00e3o apoiados por cerca de quatro mil soldados do Ruanda, uma acusa\u00e7\u00e3o que Kigali negou.<\/p>\n\n\n\n<p>As equipas t\u00e9cnicas dos pa\u00edses j\u00e1 iniciaram o projecto, que dever\u00e1 ser formalmente assinado em Washington na pr\u00f3xima semana.<\/p>\n\n\n\n<p>O projecto de acordo de paz visa p\u00f4r fim aos combates no leste da RDC, onde os rebeldes do M23, apoiados pelo Ruanda, fizeram avan\u00e7os significativos no in\u00edcio do ano, capturando a cidade estrat\u00e9gica de Goma e a cidade de Bukavu.<\/p>\n\n\n\n<p>&#8220;O acordo inclui disposi\u00e7\u00f5es sobre o respeito pela integridade territorial e a proibi\u00e7\u00e3o de hostilidades; desmobiliza\u00e7\u00e3o, desarmamento e integra\u00e7\u00e3o condicional de grupos armados n\u00e3o estatais&#8221;, refere o comunicado publicado na p\u00e1gina do Departamento de Estado na internet.<\/p>\n\n\n\n<p>O secret\u00e1rio de Estado dos EUA, Marco Rubio, assistir\u00e1 \u00e0 cerim\u00f3nia oficial de assinatura na pr\u00f3xima semana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"735\" height=\"450\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/06\/1000317705.jpg\" alt=\"\" class=\"wp-image-6196\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/06\/1000317705.jpg 735w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/06\/1000317705-300x184.jpg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/06\/1000317705-716x438.jpg 716w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/figure>\n\n\n\n<p>O acordo anunciado na quarta-feira baseia-se numa declara\u00e7\u00e3o de princ\u00edpios assinada entre os dois pa\u00edses em Abril e constituir\u00e1 um avan\u00e7o para a administra\u00e7\u00e3o do Presidente Donald Trump, que pretende p\u00f4r termo ao conflito no leste da RDC e atrair milhares de milh\u00f5es de d\u00f3lares de investimento ocidental para a regi\u00e3o rica em minerais.<\/p>\n\n\n\n<p>Ainda n\u00e3o \u00e9 claro se a Alian\u00e7a do Rio Congo &#8211; uma coliga\u00e7\u00e3o de grupos rebeldes que inclui o M23 &#8211; ir\u00e1 aderir ao acordo.<\/p>\n\n\n\n<p>Lembrando que os representantes ruandeses e congoleses chegaram por duas vezes a acordos no ano passado, sob a media\u00e7\u00e3o de Angola, sobre a retirada de tropas e opera\u00e7\u00f5es conjuntas contra o grupo rebelde hutu ruand\u00eas FDLR, mas os ministros de ambos os pa\u00edses n\u00e3o aprovaram os acordos.<\/p>\n\n\n\n<p>Angola deixou de ser mediadora em Mar\u00e7o, ap\u00f3s v\u00e1rias tentativas falhadas de resolver a escalada da ofensiva rebelde apoiada pelo Ruanda no leste da RDC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Rep\u00fablica Democr\u00e1tica do Congo e o Ruanda v\u00e3o assinar um acordo de paz a 27 de Junho, segundo uma declara\u00e7\u00e3o conjunta com o Departamento de Estado dos EUA. Um [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-6193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=6193"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6193\/revisions"}],"predecessor-version":[{"id":6197,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6193\/revisions\/6197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/6195"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=6193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=6193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=6193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}