{"id":6242,"date":"2025-06-24T11:03:00","date_gmt":"2025-06-24T11:03:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=6242"},"modified":"2025-06-24T08:54:17","modified_gmt":"2025-06-24T08:54:17","slug":"representante-da-onu-destaca-iniciativas-do-pais","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/06\/24\/representante-da-onu-destaca-iniciativas-do-pais\/","title":{"rendered":"Representante da ONU Destaca Iniciativas do Pa\u00eds"},"content":{"rendered":"\n<p>A representante especial do Secret\u00e1rio-Geral das Na\u00e7\u00f5es Unidas para o Combate \u00e0 Viol\u00eancia contra a Crian\u00e7a, Najat Maalla M\u2019jid, destacou, segunda-feira, em Luanda, as iniciativas de Angola na promo\u00e7\u00e3o dos direitos da crian\u00e7a e no combate \u00e0 viol\u00eancia<\/p>\n\n\n\n<p>Em visita oficial ao pa\u00eds, a respons\u00e1vel disse que Angola tem demonstrado um compromisso firme com a causa, especialmente ap\u00f3s a ades\u00e3o \u00e0 iniciativa global pelo fim da viol\u00eancia contra crian\u00e7as e a subscri\u00e7\u00e3o da Declara\u00e7\u00e3o de Bogot\u00e1.<\/p>\n\n\n\n<p>No primeiro dia da miss\u00e3o, Najat M\u2019jid manteve encontros com diversas institui\u00e7\u00f5es de protec\u00e7\u00e3o infantil e visitou o Lar Kuzola, em Luanda, onde avaliou as condi\u00e7\u00f5es de acolhimento de crian\u00e7as afastadas do conv\u00edvio familiar. A respons\u00e1vel esteve, ainda, no Call Center de den\u00fancias do Instituto Nacional da Crian\u00e7a (INAC), denominado SOS Crian\u00e7a.<\/p>\n\n\n\n<p>Najat Maalla M\u2019jid trabalha no pa\u00eds entre os dias 23 e 28 de Junho, no quadro de uma agenda que visa fortalecer a coopera\u00e7\u00e3o com o Governo angolano.<\/p>\n\n\n\n<p>De acordo com o director-geral do Instituto Nacional da Crian\u00e7a (INAC), Paulo Kalesi, a agenda da representante do Secret\u00e1rio-Geral das Na\u00e7\u00f5es Unidas inclui, ainda, um encontro com os deputados infantis das 21 prov\u00edncias, bem como a participa\u00e7\u00e3o no IX F\u00f3rum Nacional da Crian\u00e7a, a decorrer amanh\u00e3.<\/p>\n\n\n\n<p>Paulo Kalesi salientou que, com essa visita, a expectativa \u00e9 que o pa\u00eds reforce a sua posi\u00e7\u00e3o como refer\u00eancia no continente no que diz respeito ao combate \u00e0 viol\u00eancia a crian\u00e7as e o cumprimento dos compromissos internacionais de protec\u00e7\u00e3o infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A representante especial do Secret\u00e1rio-Geral das Na\u00e7\u00f5es Unidas para o Combate \u00e0 Viol\u00eancia contra a Crian\u00e7a, Najat Maalla M\u2019jid, destacou, segunda-feira, em Luanda, as iniciativas de Angola na promo\u00e7\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[343],"tags":[],"class_list":["post-6242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=6242"}],"version-history":[{"count":1,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6242\/revisions"}],"predecessor-version":[{"id":6243,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6242\/revisions\/6243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/6244"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=6242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=6242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=6242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}