{"id":6421,"date":"2025-07-01T11:02:00","date_gmt":"2025-07-01T11:02:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=6421"},"modified":"2025-07-01T09:51:43","modified_gmt":"2025-07-01T09:51:43","slug":"russia-lanca-maior-ataque-aereo-contra-ucrania","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/07\/01\/russia-lanca-maior-ataque-aereo-contra-ucrania\/","title":{"rendered":"R\u00fassia Lan\u00e7a Maior Ataque A\u00e9reo Contra Ucr\u00e2nia"},"content":{"rendered":"\n<p>A R\u00fassia fez, na \u00faltima madrugada,  o maior ataque a\u00e9reo contra a Ucr\u00e2nia desde o in\u00edcio da invas\u00e3o, com um total de 537 lan\u00e7amentos, incluindo 477 drones e 60 m\u00edsseis, informou a for\u00e7a a\u00e9rea ucraniana. <\/p>\n\n\n\n<p>Destes, 249 foram abatidos e 226 foram perdidos, provavelmente por terem sido eletronicamente bloqueados.<\/p>\n\n\n\n<p>Para al\u00e9m dos drones, a for\u00e7a a\u00e9rea de Kiev enumerou quatro m\u00edsseis Kh-47M2 Kinzhal, sete m\u00edsseis bal\u00edsticos Iskander-M\/KN-23, um dos quais foi abatido; 41 m\u00edsseis de cruzeiro Kh-101\/Iskander-K, dos quais 33 foram abatidos e um desapareceu dos radares; cinco m\u00edsseis de cruzeiro Kalibr (quatro abatidos) e tr\u00eas m\u00edsseis antia\u00e9reos S-300.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"536\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-01-at-10.15.42-1.jpeg\" alt=\"\" class=\"wp-image-6424\" style=\"width:470px;height:auto\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-01-at-10.15.42-1.jpeg 750w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-01-at-10.15.42-1-300x214.jpeg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-01-at-10.15.42-1-716x512.jpeg 716w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>Yuriy Ihnat, chefe de comunica\u00e7\u00f5es da for\u00e7a a\u00e9rea ucraniana, disse \u00e0 Associated Press que o ataque noturno foi &#8220;o ataque a\u00e9reo mais maci\u00e7o&#8221; no pa\u00eds, tendo em conta tanto os drones como os v\u00e1rios tipos de m\u00edsseis. O ataque teve como alvos regi\u00f5es de toda a Ucr\u00e2nia, incluindo a parte ocidentall, longe da linha da frente.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es oficiais da Ucr\u00e2nia, duas pessoas morreram e 12, incluindo duas crian\u00e7as, ficaram feridas nos ataques. Em Kiev, a popula\u00e7\u00e3o se abrigou em abrigos antibomba e em esta\u00e7\u00f5es de metro.<\/p>\n\n\n\n<p>J\u00e1 o ex\u00e9rcito da R\u00fassia afirma que os ataques atingiram alvos do complexo industrial-militar ucraniano e refinarias de petr\u00f3leo. Tamb\u00e9m informou que tr\u00eas drones ucranianos foram interceptados durante a noite.<\/p>\n\n\n\n<p>A nova rodada de ataques coloca em xeque novas negocia\u00e7\u00f5es de paz na regi\u00e3o. O presidente ucraniano Volodymyr Zelensky declarou em uma rede social que \u201cMoscovo n\u00e3o vai parar enquanto tiver capacidade de lan\u00e7ar ataques massivos\u201d. Ele tamb\u00e9m pediu mais press\u00e3o sobre a R\u00fassia, que j\u00e1 \u00e9 alvo de in\u00fameras san\u00e7\u00f5es de pa\u00edses europeus e dos EUA.<\/p>\n\n\n\n<p>O governo ucraniano tenta sair de um acordo internacional que pro\u00edbe o uso de minas terrestres, alegando que a a R\u00fassia n\u00e3o faz parte desta conven\u00e7\u00e3o e tem feito uso do armamento.<\/p>\n\n\n\n<p>J\u00e1 o presidente Volodymyr Zelensky adiantou que o piloto de um ca\u00e7a F-16 morreu durante a noite, enquanto tentava intercetar o ataque.<\/p>\n\n\n\n<p>O presidente da Ucr\u00e2nia j\u00e1 ordenou uma investiga\u00e7\u00e3o a esta morte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A R\u00fassia fez, na \u00faltima madrugada, o maior ataque a\u00e9reo contra a Ucr\u00e2nia desde o in\u00edcio da invas\u00e3o, com um total de 537 lan\u00e7amentos, incluindo 477 drones e 60 m\u00edsseis, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[343],"tags":[],"class_list":["post-6421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=6421"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6421\/revisions"}],"predecessor-version":[{"id":6425,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6421\/revisions\/6425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/6423"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=6421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=6421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=6421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}