{"id":6670,"date":"2025-07-11T15:03:00","date_gmt":"2025-07-11T15:03:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=6670"},"modified":"2025-07-11T14:39:15","modified_gmt":"2025-07-11T14:39:15","slug":"negociacoes-entre-a-republica-democratica-do-congo-e-os-rebeldes-do-m23-avancam-pacificamente","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/07\/11\/negociacoes-entre-a-republica-democratica-do-congo-e-os-rebeldes-do-m23-avancam-pacificamente\/","title":{"rendered":"Negocia\u00e7\u00f5es entre a Rep\u00fablica Democr\u00e1tica do Congo e os Rebeldes do M23 Avan\u00e7am Pacificamente"},"content":{"rendered":"\n<p>As negocia\u00e7\u00f5es entre a Rep\u00fablica Democr\u00e1tica do Congo (RDC) e o grupo rebelde M23, apoiado pelo Ruanda, est\u00e3o a andar em dire\u00e7\u00e3o a uma resolu\u00e7\u00e3o pac\u00edfica. De acordo com a fonte diplom\u00e1tica \u00e0 AFP, enquanto as negocia\u00e7\u00f5es prosseguem entre as duas partes no Catar.<\/p>\n\n\n\n<p>Negociadores congoleses e do M23 est\u00e3o nesta altura a trabalhar com mediadores catarianos para tentar superar os obst\u00e1culos restantes.<\/p>\n\n\n\n<p>Recentemente, o M23 havia pedido a retomada das negocia\u00e7\u00f5es para resolver as quest\u00f5es pendentes no acordo de paz facilitado pelos Estados Unidos da America e assinado em Washington no m\u00eas passado entre Kinshasa e Kigali.<\/p>\n\n\n\n<p>O tratado visa p\u00f4r fim aos combates que j\u00e1 ceifaram milhares de vidas no leste do Congo. Mas, a menos que o M23, o grupo armado mais proeminente que luta na regi\u00e3o, concorde com ele, \u00e9 improv\u00e1vel que o conflito termine.<\/p>\n\n\n\n<p>O grupo rebelde M23, apoiado por Ruanda, \u00e9 o grupo armado mais proeminente no conflito, e seu grande avan\u00e7o no in\u00edcio deste ano deixou corpos nas ruas. <\/p>\n\n\n\n<p>Com sete milh\u00f5es de pessoas deslocadas no Congo, as Na\u00e7\u00f5es Unidas a chamaram de &#8220;uma das crises humanit\u00e1rias mais prolongadas, complexas e graves da Terra&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As negocia\u00e7\u00f5es entre a Rep\u00fablica Democr\u00e1tica do Congo (RDC) e o grupo rebelde M23, apoiado pelo Ruanda, est\u00e3o a andar em dire\u00e7\u00e3o a uma resolu\u00e7\u00e3o pac\u00edfica. De acordo com a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-6670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=6670"}],"version-history":[{"count":3,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6670\/revisions"}],"predecessor-version":[{"id":6674,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/6670\/revisions\/6674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/6676"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=6670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=6670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=6670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}