{"id":7641,"date":"2025-08-29T11:41:14","date_gmt":"2025-08-29T11:41:14","guid":{"rendered":"https:\/\/zango.co.ao\/?p=7641"},"modified":"2025-08-29T11:41:16","modified_gmt":"2025-08-29T11:41:16","slug":"novo-implante-cerbro-espinhal-permite-paraplegico-voltar-andar-em-24-horas","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/08\/29\/novo-implante-cerbro-espinhal-permite-paraplegico-voltar-andar-em-24-horas\/","title":{"rendered":"Novo implante C\u00e9rbro-espinhal Permite Parapl\u00e9gico Voltar Andar em 24 horas"},"content":{"rendered":"\n<p>Pesquisadores da Universidade Fudan, em Xangai, desenvolveram uma interface c\u00e9rebro-espinhal inovadora que reactiva nervos adormecidos, permitindo que pacientes paralisados recuperem movimentos nas pernas em apenas 24 horas ap\u00f3s a cirurgia.<\/p>\n\n\n\n<p>A tecnologia envolve a implanta\u00e7\u00e3o minimamente invasiva de dois eletrodos de aproximadamente um mil\u00edmetro de di\u00e2metro no c\u00f3rtex, motor do c\u00e9rebro e na medula espinhal.<\/p>\n\n\n\n<p> Esses dispositivos criam uma &#8220;ponte neural&#8221; que restabelece a comunica\u00e7\u00e3o entre o c\u00e9rebro e os m\u00fasculos das pernas, utilizando intelig\u00eancia artificial para decodificar sinais cerebrais e estimular directamente os nervos respons\u00e1veis pelo movimento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"638\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14.jpeg\" alt=\"\" class=\"wp-image-7645\" style=\"width:461px;height:auto\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14.jpeg 850w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14-300x225.jpeg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14-768x576.jpeg 768w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14-716x537.jpeg 716w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.14-820x615.jpeg 820w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p>Em testes cl\u00ednicos realizados, quatro pacientes com paralisia severa devido a les\u00f5es na medula espinhal foram submetidos ao procedimento. O primeiro paciente, um homem de 34 anos, paralisado h\u00e1 dois anos ap\u00f3s uma queda, conseguiu mover as pernas no dia seguinte \u00e0 cirurgia e, em duas semanas, caminhava mais de cinco metros com aux\u00edlio de um suporte.<\/p>\n\n\n\n<p>Diferente de estudos anteriores, que exigem meses para mostrar progresso, este sistema reduz drasticamente o tempo de recupera\u00e7\u00e3o.<\/p>\n\n\n\n<p>Esta revolu\u00e7\u00e3o m\u00e9dica representa uma nova era na reabilita\u00e7\u00e3o de les\u00f5es medulares, oferecendo esperan\u00e7a a milh\u00f5es de pessoas com paralisia. Os pesquisadores planeam expandir os estudos cl\u00ednicos e aprimorar a tecnologia para torn\u00e1-la acess\u00edvel a um n\u00famero maior de pacientes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18.jpeg\" alt=\"\" class=\"wp-image-7646\" style=\"width:462px;height:auto\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18.jpeg 799w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18-300x200.jpeg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18-768x512.jpeg 768w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18-716x478.jpeg 716w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-29-at-11.18.18-332x222.jpeg 332w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisadores da Universidade Fudan, em Xangai, desenvolveram uma interface c\u00e9rebro-espinhal inovadora que reactiva nervos adormecidos, permitindo que pacientes paralisados recuperem movimentos nas pernas em apenas 24 horas ap\u00f3s a cirurgia. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":7643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-7641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=7641"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7641\/revisions"}],"predecessor-version":[{"id":7647,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7641\/revisions\/7647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/7643"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=7641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=7641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=7641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}