{"id":7771,"date":"2025-09-04T13:01:00","date_gmt":"2025-09-04T13:01:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=7771"},"modified":"2025-09-04T12:03:47","modified_gmt":"2025-09-04T12:03:47","slug":"ex-ministro-da-justica-congoles-condenado-a-tres-anos-de-trabalho-forcado-por-porrupcao","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/09\/04\/ex-ministro-da-justica-congoles-condenado-a-tres-anos-de-trabalho-forcado-por-porrupcao\/","title":{"rendered":"Ex-ministro da Justi\u00e7a Congol\u00eas Condenado a Tr\u00eas Anos de Trabalho For\u00e7ado por Porrup\u00e7\u00e3o"},"content":{"rendered":"\n<p>O Tribunal de Cassa\u00e7\u00e3o condenou nesta ter\u00e7a-feira, o ex-ministro da Justi\u00e7a da Rep\u00fablica Democr\u00e1tica do Congo (RDC), Constant Mutamba, a tr\u00eas anos de trabalhos for\u00e7ados por desvio de fundos p\u00fablicos avaliados em 19 milh\u00f5es de d\u00f3lares destinados \u00e0 constru\u00e7\u00e3o de uma pris\u00e3o no norte do pa\u00eds.<\/p>\n\n\n\n<p>O tribunal decidiu que Mutamba agiu com inten\u00e7\u00e3o de enriquecimento il\u00edcito e ignorou procedimentos legais.<\/p>\n\n\n\n<p>Durante o julgamento as ruas pr\u00f3ximas ao tribunal foram bloqueadas e as for\u00e7as de seguran\u00e7a mobilizadas para prevenir dist\u00farbios.<\/p>\n\n\n\n<p>O ex-ministro renunciou ao cargo em Junho, era conhecido por sua ret\u00f3rica anti-corrup\u00e7\u00e3o e chegou a propor a pena de morte para jornalistas que cobrissem ac\u00e7\u00f5es de rebeldes apoiados por Ruanda.<\/p>\n\n\n\n<p>Sua condena\u00e7\u00e3o gerou protestos de apoiadores, resultando em confrontos com a pol\u00edcia em Kinshasa. Este caso destaca os desafios enfrentados pela RDC na luta contra corrup\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Cassa\u00e7\u00e3o condenou nesta ter\u00e7a-feira, o ex-ministro da Justi\u00e7a da Rep\u00fablica Democr\u00e1tica do Congo (RDC), Constant Mutamba, a tr\u00eas anos de trabalhos for\u00e7ados por desvio de fundos p\u00fablicos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-7771","post","type-post","status-publish","format-standard","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=7771"}],"version-history":[{"count":4,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7771\/revisions"}],"predecessor-version":[{"id":7777,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7771\/revisions\/7777"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=7771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=7771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=7771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}