{"id":7933,"date":"2025-09-11T17:01:00","date_gmt":"2025-09-11T17:01:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=7933"},"modified":"2025-09-11T14:36:39","modified_gmt":"2025-09-11T14:36:39","slug":"aliado-de-donald-trump-morre-baleado-em-universidade-no-estado-de-utah","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/09\/11\/aliado-de-donald-trump-morre-baleado-em-universidade-no-estado-de-utah\/","title":{"rendered":"Aliado de Donald Trump Morre Baleado em Universidade no Estado de Utah"},"content":{"rendered":"\n<p>O activista e influenciador de ultradireita Charlie Kirk, de 31 anos, um dos principais aliados do Presidente dos Estados Unidos, Donald Trump, foi baleado e morto na quarta-feira (10) durante um evento ao ar livre na Universidade de Utah Valley, no estado de Utah. <\/p>\n\n\n\n<p>Kirk chegou a ser levado de urg\u00eancia para um hospital pr\u00f3ximo, onde foi submetido a uma cirurgia, mas n\u00e3o resistiu aos ferimentos.<\/p>\n\n\n\n<p>Charlie Kirk era uma figura central na mobiliza\u00e7\u00e3o da juventude republicana e ganhou destaque nacional pelo seu papel activo na estrat\u00e9gia eleitoral de Trump. Reconhecido pela sua capacidade de atrair jovens para o conservadorismo, era considerado uma das vozes mais influentes da direita norte-americana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-1024x682.jpeg\" alt=\"\" class=\"wp-image-7936\" style=\"width:554px;height:auto\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-1024x682.jpeg 1024w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-300x200.jpeg 300w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-768x512.jpeg 768w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-716x477.jpeg 716w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-332x222.jpeg 332w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53-820x546.jpeg 820w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-11-at-13.41.53.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O ataque ocorreu quando Kirk discursava sob uma tenda perante uma multid\u00e3o de estudantes e apoiantes. V\u00eddeos gravados no local mostram o momento em que um \u00fanico disparo ecoa, atingiu o pesco\u00e7o do orador, que caiu imediatamente ao solo, sangrando abundantemente.<\/p>\n\n\n\n<p>Em nota nas redes sociais, Trump confirmou a morte e lamentou a perda do aliado: \u201cO grande, e at\u00e9 lend\u00e1rio, Charlie Kirk est\u00e1 morto. Ningu\u00e9m compreendia ou tinha o cora\u00e7\u00e3o da juventude dos Estados Unidos da Am\u00e9rica melhor do que Charlie. Ele era amado e admirado por todos, especialmente por mim, e agora n\u00e3o est\u00e1 mais entre n\u00f3s. Melania e eu expressamos nossas condol\u00eancias \u00e0 sua bela esposa Erika e \u00e0 sua fam\u00edlia. Charlie, n\u00f3s te amamos!\u201d escreveu o Presidente na plataforma Truth Social.<\/p>\n\n\n\n<p>O governador de Utah, Spencer Cox, reagiu ao ataque classificando-o como crime pol\u00edtico: \u201cEste \u00e9 um dia sombrio para o nosso estado. \u00c9 um dia tr\u00e1gico para a nossa na\u00e7\u00e3o. Quero deixar bem claro: este \u00e9 um assassinato pol\u00edtico\u201d.<\/p>\n\n\n\n<p>A Universidade de Utah Valley divulgou inicialmente que um suspeito tinha sido detido logo ap\u00f3s o disparo. Imagens mostraram um homem idoso a ser levado pela pol\u00edcia, mas a imprensa norte-americana confirmou que ele foi libertado, levantando a hip\u00f3tese de o verdadeiro autor estar em fuga.<\/p>\n\n\n\n<p>A morte de Charlie Kirk gerou ampla como\u00e7\u00e3o nos Estados Unidos, intensificando o debate sobre a viol\u00eancia pol\u00edtica e a seguran\u00e7a de figuras p\u00fablicas em eventos abertos ao p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O activista e influenciador de ultradireita Charlie Kirk, de 31 anos, um dos principais aliados do Presidente dos Estados Unidos, Donald Trump, foi baleado e morto na quarta-feira (10) durante [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[343],"tags":[],"class_list":["post-7933","post","type-post","status-publish","format-standard","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=7933"}],"version-history":[{"count":3,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7933\/revisions"}],"predecessor-version":[{"id":7940,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/7933\/revisions\/7940"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=7933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=7933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=7933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}