{"id":8001,"date":"2025-09-16T17:01:18","date_gmt":"2025-09-16T17:01:18","guid":{"rendered":"https:\/\/zango.co.ao\/?p=8001"},"modified":"2025-09-16T16:24:37","modified_gmt":"2025-09-16T16:24:37","slug":"oms-inicia-vacinacao-contra-o-ebola-na-rdc","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/09\/16\/oms-inicia-vacinacao-contra-o-ebola-na-rdc\/","title":{"rendered":"OMS Inicia Vacina\u00e7\u00e3o Contra o \u00c9bola na RDC"},"content":{"rendered":"\n<p>A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) come\u00e7ou a vacinar profissionais de sa\u00fade da linha de frente e contactos de indiv\u00edduos infectados, em resposta a um novo surto de \u00c9bola na prov\u00edncia de Kasai, na Rep\u00fablica Democr\u00e1tica do Congo (RDC).<\/p>\n\n\n\n<p>Um total inicial de 400 doses da vacina Ervebo, contra o \u00c9bola, foi entregue \u00e0 cidade de Bulape, epicentro do surto, a partir de um estoque nacional de duas mil doses.<\/p>\n\n\n\n<p>O Grupo de Coordena\u00e7\u00e3o Internacional para o Fornecimento de Vacinas aprovou o envio de mais 45 mil doses para ajudar a conter a propaga\u00e7\u00e3o.<\/p>\n\n\n\n<p>O surto, declarado no in\u00edcio de Setembro, j\u00e1 provocou pelo menos 16 mortes, com cerca de 68 casos suspeitos e 20 confirmados.<\/p>\n\n\n\n<p>Dado o elevado risco de propaga\u00e7\u00e3o interna, h\u00e1 preocupa\u00e7\u00e3o com poss\u00edveis casos em pa\u00edses vizinhos, como Angola. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"576\" height=\"342\" src=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/1000466787.jpg\" alt=\"\" class=\"wp-image-8038\" srcset=\"https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/1000466787.jpg 576w, https:\/\/zango.co.ao\/wp-content\/uploads\/2025\/09\/1000466787-300x178.jpg 300w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p>A \u00c9bola \u00e9 uma doen\u00e7a viral grave e frequentemente fatal que afecta seres humanos e primatas. \u00c9 causada pelo v\u00edrus Ebola, pertencente \u00e0 fam\u00edlia Filoviridae.<\/p>\n\n\n\n<p>O custo projectado pela OMS para o actual surto nos pr\u00f3ximos tr\u00eas meses \u00e9 de 20 milh\u00f5es de d\u00f3lares, enquanto o plano de resposta nacional da RDC est\u00e1 estimado em USD 78 milh\u00f5es, disse Otim.<\/p>\n\n\n\n<p>Uma preocupa\u00e7\u00e3o importante tem sido o impacto dos recentes cortes de financiamento nos EUA.<\/p>\n\n\n\n<p>Os Estados Unidos apoiaram a resposta aos anteriores surtos de \u00c9bola na RDC, incluindo em 2021, quando a Ag\u00eancia dos EUA para o Desenvolvimento Internacional forneceu at\u00e9 11,5 milh\u00f5es de d\u00f3lares para apoiar os esfor\u00e7os em toda a \u00c1frica.<\/p>\n\n\n\n<p>O \u00c9bola \u00e9 uma febre hemorr\u00e1gica grave que se transmite por contacto directo com sangue ou fluidos corporais de pessoas e animais infectados, com uma taxa de mortalidade que, segundo a Organiza\u00e7\u00e3o Mundial da Sa\u00fade, oscila entre os 60 e 80 por cento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) come\u00e7ou a vacinar profissionais de sa\u00fade da linha de frente e contactos de indiv\u00edduos infectados, em resposta a um novo surto de \u00c9bola na [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-8001","post","type-post","status-publish","format-standard","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=8001"}],"version-history":[{"count":5,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8001\/revisions"}],"predecessor-version":[{"id":8039,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8001\/revisions\/8039"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=8001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=8001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=8001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}