{"id":8956,"date":"2025-11-02T13:02:00","date_gmt":"2025-11-02T13:02:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=8956"},"modified":"2025-11-03T07:33:10","modified_gmt":"2025-11-03T07:33:10","slug":"o-novo-navegador-da-openai-com-chatgpt-embutido-e-tudo-que-o-chrome-queria-ser","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/11\/02\/o-novo-navegador-da-openai-com-chatgpt-embutido-e-tudo-que-o-chrome-queria-ser\/","title":{"rendered":"O Novo Navegador da OpenAI com ChatGPT Embutido \u00e9 Tudo que o Chrome Queria Ser"},"content":{"rendered":"\n<p>A OpenAI anunciou na ter\u00e7a-feira 22 de Outubro o ChatGPT Atlas, um novo navegador que promete redefinir a forma como os usu\u00e1rios exploram a internet. Com o ChatGPT integrado de forma nativa, o Atlas leva a Intelig\u00eancia Artificial generativa para dentro da experi\u00eancia de navega\u00e7\u00e3o, eliminando a necessidade de trocar de abas, copiar e colar textos ou alternar entre buscadores e o assistente.<\/p>\n\n\n\n<p>Diferente de navegadores tradicionais como o Chrome, do Google, e o Safari, da Apple, o Atlas foi concebido desde o in\u00edcio com um assistente conversacional no centro da experi\u00eancia. O navegador entende o contexto do usu\u00e1rio levando em conta hist\u00f3rico de navega\u00e7\u00e3o, p\u00e1ginas abertas e sites logados \u2014 para oferecer respostas e sugest\u00f5es personalizadas em tempo real.<\/p>\n\n\n\n<p>\u201cO objectivo \u00e9 aproximar o navegador do que chamamos de um verdadeiro superassistente \u2014 que entende o seu mundo e te ajuda a alcan\u00e7ar seus objectivos\u201d, afirmou Fidji Simo, CEO de Aplica\u00e7\u00f5es da OpenAI, em comunicado oficial.<\/p>\n\n\n\n<p><strong>O navegador que entende o usu\u00e1rio<\/strong><br>No Atlas, o ChatGPT acompanha o usu\u00e1rio em toda a web. \u00c9 poss\u00edvel abrir uma nova aba e pedir: \u201corganize minhas abas\u201d ou \u201cmostre os sapatos que vi ontem\u201d \u2014 e o assistente executa as ac\u00e7\u00f5es automaticamente. O sistema tamb\u00e9m pode guardar detalhes da navega\u00e7\u00e3o para retomar tarefas anteriores ou automatizar fluxos de trabalho.<\/p>\n\n\n\n<p>O navegador permite ainda activar ou desativar o armazenamento de mem\u00f3rias, oferecendo controlo sobre o que o ChatGPT pode acessar e lembrar. Segundo a OpenAI, o conte\u00fado da navega\u00e7\u00e3o n\u00e3o \u00e9 usado para treinar modelos de IA, e o modo an\u00f4nimo segue dispon\u00edvel.<\/p>\n\n\n\n<p><strong>Atlas x Chrome x Safari: as diferen\u00e7as fundamentais<\/strong><br>Enquanto Chrome e Safari continuam centrados na busca tradicional e na integra\u00e7\u00e3o com ecossistemas espec\u00edficos (Google e Apple, respectivamente), o Atlas prop\u00f5e uma experi\u00eancia centrada na intera\u00e7\u00e3o em linguagem natural.<\/p>\n\n\n\n<p>Chrome: prioriza velocidade, sincroniza\u00e7\u00e3o com o Google e integra\u00e7\u00e3o com servi\u00e7os como Docs, Gmail e Drive. Sua intelig\u00eancia artificial est\u00e1 ligada principalmente ao motor de busca e \u00e0s recomenda\u00e7\u00f5es do ecossistema Google.<\/p>\n\n\n\n<p>Safari: foca em privacidade e efici\u00eancia energ\u00e9tica, principalmente no ambiente Apple. O navegador mant\u00e9m uma abordagem conservadora quanto \u00e0 coleta de dados e ao uso de IA.<\/p>\n\n\n\n<p>Atlas: introduz uma camada conversacional e contextual, na qual o usu\u00e1rio interage com a web por meio do ChatGPT. Ele n\u00e3o apenas ajuda a encontrar informa\u00e7\u00f5es, mas tamb\u00e9m actua \u2014 preenchendo formul\u00e1rios, resumindo p\u00e1ginas, organiza conte\u00fado e at\u00e9 realiza tarefas via modo agente, em uma pr\u00e9via dispon\u00edvel para os planos Plus, Pro e Business.<\/p>\n\n\n\n<p>Essa abordagem transforma o navegador em um ambiente de produtividade aut\u00f4nomo, e n\u00e3o apenas um portal de acesso \u00e0 internet.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia e impacto<\/strong><br>Com o lan\u00e7amento, a OpenAI expande seu alcance al\u00e9m do chat e entra no territ\u00f3rio dos navegadores, um dos mercados mais dominados da tecnologia moderna. O Chrome, por exemplo, det\u00e9m mais de 60 por cento de participa\u00e7\u00e3o global, enquanto o Safari lidera entre os usu\u00e1rios de macOS e iOS.<\/p>\n\n\n\n<p>O Atlas chega primeiro para macOS, dispon\u00edvel gratuitamente e para usu\u00e1rios dos planos pagos do ChatGPT (Free, Plus, Pro e Go). As vers\u00f5es para Windows, iOS e Android ser\u00e3o lan\u00e7adas em breve.<\/p>\n\n\n\n<p>O movimento marca um novo passo na estrat\u00e9gia da OpenAI de criar um ecossistema completo em torno do ChatGPT, posicionando a empresa n\u00e3o apenas como fornecedora de modelos de linguagem, mas como desenvolvedora de plataformas de uso cotidiano.<\/p>\n\n\n\n<p><strong>Fote:<\/strong> forbes.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A OpenAI anunciou na ter\u00e7a-feira 22 de Outubro o ChatGPT Atlas, um novo navegador que promete redefinir a forma como os usu\u00e1rios exploram a internet. Com o ChatGPT integrado de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[649],"tags":[],"class_list":["post-8956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=8956"}],"version-history":[{"count":5,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8956\/revisions"}],"predecessor-version":[{"id":9096,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/8956\/revisions\/9096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/8958"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=8956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=8956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=8956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}