{"id":9449,"date":"2025-11-27T11:02:00","date_gmt":"2025-11-27T11:02:00","guid":{"rendered":"https:\/\/zango.co.ao\/?p=9449"},"modified":"2025-11-27T09:31:02","modified_gmt":"2025-11-27T09:31:02","slug":"oficiais-militares-assumem-o-controlo-total-na-guine-bissau","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/11\/27\/oficiais-militares-assumem-o-controlo-total-na-guine-bissau\/","title":{"rendered":"Oficiais Militares Assumem o Controlo Total na Guin\u00e9-Bissau"},"content":{"rendered":"\n<p>Nesta quarta\u2011feira, 26, oficiais das For\u00e7as Armadas da Guin\u00e9\u2011Bissau declararam, em cadeia da televis\u00e3o estatal, que tomaram o \u201ccontrolo total\u201d do pa\u00eds. A opera\u00e7\u00e3o ocorreu \u00e0s v\u00e9speras da divulga\u00e7\u00e3o dos resultados provis\u00f3rios das elei\u00e7\u00f5es presidenciais e legislativas e antecipou mais uma turbul\u00eancia na hist\u00f3ria pol\u00edtica do pa\u00eds.<br>\u200e<br>\u200eEm comunicado, o alto comando militar afirmou ter &#8220;assumido os plenos poderes do Estado da Rep\u00fablica da Guin\u00e9-Bissau&#8221;.<br>\u200e<br>\u200eA declara\u00e7\u00e3o afirmava que essa medida era uma rea\u00e7\u00e3o \u00e0 &#8220;descoberta de um plano em andamento&#8221; com o objectivo de desestabilizar o pa\u00eds, tentando &#8220;manipular os resultados eleitorais&#8221;. O an\u00fancio dos militares ocorreu um dia depois de os dois principais candidatos na acirrada elei\u00e7\u00e3o presidencial da semana passada terem declarado vit\u00f3ria.<br>\u200e<br>\u200eMais cedo, foram ouvidos tiros em v\u00e1rios locais da capital, Bissau, incluindo o pal\u00e1cio presidencial, embora n\u00e3o esteja claro quem foram os respons\u00e1veis.<br>\u200e<br>\u200eO porta-voz militar, Dinis N&#8217;Tchama, afirmou que os soldados formaram &#8220;o alto comando militar para o restabelecimento da ordem&#8221;, que governar\u00e1 o pa\u00eds at\u00e9 segunda ordem.<br>\u200e<br>\u200e&#8221;Suspender, at\u00e9 novas ordens, todas as institui\u00e7\u00f5es da Rep\u00fablica da Guin\u00e9-Bissau, suspender, at\u00e9 novas ordens, as actividades de todos os meios de comunica\u00e7\u00e3o, suspender imediatamente o actual processo eleitoral, fechar as fronteiras terrestres, mar\u00edtimas e o espa\u00e7o a\u00e9reo nacional&#8221;, disse ele.<br>\u200e<br>\u200eJornalistas na capital relataram ter visto estradas que davam acesso ao pal\u00e1cio presidencial bloqueadas, com postos de controle ocupados por soldados fortemente armados e mascarados.<br>\u200e<br>\u200eA comiss\u00e3o eleitoral deveria anunciar os resultados provis\u00f3rios das elei\u00e7\u00f5es presidenciais e parlamentares hoje.<br>\u200e<br>\u200eUm membro importante do grupo internacional de observadores eleitorais afirmou que o chefe da comiss\u00e3o eleitoral foi preso e que o escrit\u00f3rio da comiss\u00e3o foi isolado pelos militares.<br>\u200e<br>\u200eO portal de not\u00edcias franc\u00eas Jeune Afrique citou Embal\u00f3 dizendo que foi preso no que chamou de golpe liderado pelo chefe do Estado-Maior do Ex\u00e9rcito. Ele afirmou n\u00e3o ter sofrido viol\u00eancia.<br>\u200e<br>\u200eA Guin\u00e9\u2011Bissau j\u00e1 viveu diversos golpes de Estado desde a independ\u00eancia, em 1974 e este marca um novo cap\u00edtulo de instabilidade. As elei\u00e7\u00f5es de 2025 foram marcadas por controv\u00e9rsias, com os dois candidatos, Embal\u00f3 e o opositor Fernando Dias da Costa.<br>\u200e<br>\u200eEmbal\u00f3 chegou ao poder em Fevereiro de 2020, mas a constitui\u00e7\u00e3o do pa\u00eds estabelece o mandato presidencial em cinco anos.<br>\u200e<br>\u200eA tomada de poder pelos militares \u00e9 o mais recente de uma s\u00e9rie de golpes de Estado e tentativas de golpe na Guin\u00e9-Bissau desde que o pa\u00eds conquistou a independ\u00eancia de Portugal em 1974.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta\u2011feira, 26, oficiais das For\u00e7as Armadas da Guin\u00e9\u2011Bissau declararam, em cadeia da televis\u00e3o estatal, que tomaram o \u201ccontrolo total\u201d do pa\u00eds. A opera\u00e7\u00e3o ocorreu \u00e0s v\u00e9speras da divulga\u00e7\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-9449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=9449"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9449\/revisions"}],"predecessor-version":[{"id":9453,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9449\/revisions\/9453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/9450"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=9449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=9449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=9449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}