{"id":9471,"date":"2025-11-28T10:18:25","date_gmt":"2025-11-28T10:18:25","guid":{"rendered":"https:\/\/zango.co.ao\/?p=9471"},"modified":"2025-11-28T10:18:28","modified_gmt":"2025-11-28T10:18:28","slug":"argelia-acolhe-conferencia-sobre-crimes-do-colonialismo-em-africa","status":"publish","type":"post","link":"https:\/\/zango.co.ao\/index.php\/2025\/11\/28\/argelia-acolhe-conferencia-sobre-crimes-do-colonialismo-em-africa\/","title":{"rendered":"Arg\u00e9lia Acolhe Confer\u00eancia sobre Crimes do Colonialismo em \u00c1frica"},"content":{"rendered":"\n<p>A Arg\u00e9lia vai acolher, nos dias 30 de Novembro a 1 de Dezembro do corrente ano a Confer\u00eancia Internacional sobre os Crimes do Colonialismo em \u00c1frica.<\/p>\n\n\n\n<p>Segundo um comunicado de imprensa enviado ao Jornal de Angola, trata-se de um importante evento continental que surge na sequ\u00eancia da Decis\u00e3o da Assembleia da Uni\u00e3o Africana 903 (XXXVIII), adoptada em Fevereiro de 2025.<\/p>\n\n\n\n<p>A nota acrescenta que a decis\u00e3o endossou a oferta do Presidente Abdelmadjid Tebboune, de organizar na Arg\u00e9lia uma confer\u00eancia dedicada \u00e0 celebra\u00e7\u00e3o e \u00e0 implementa\u00e7\u00e3o do Tema do Ano 2025: &#8220;Justi\u00e7a para os Africanos e pessoas de ascend\u00eancia africana atrav\u00e9s de repara\u00e7\u00f5es&#8221;. <\/p>\n\n\n\n<p>&#8220;Esta iniciativa insere-se na tradi\u00e7\u00e3o hist\u00f3rica da Arg\u00e9lia, que pagou um pesado tributo ao colonialismo e que continua profundamente empenhada na defesa da dignidade, da mem\u00f3ria e dos direitos dos povos africanos&#8221;, sublinha a nota.<\/p>\n\n\n\n<p>Sob a lideran\u00e7a do Presidente Abdelmadjid Tebboune, a Arg\u00e9lia trabalha para refor\u00e7ar a reflex\u00e3o e a ac\u00e7\u00e3o colectivas com vista a criminalizar o colonialismo, a escravatura, a segrega\u00e7\u00e3o racial e o <em>apartheid<\/em> como crimes contra a humanidade, em conformidade com as recomenda\u00e7\u00f5es pertinentes da Uni\u00e3o Africana.<\/p>\n\n\n\n<p>A Confer\u00eancia reunir\u00e1 ministros, juristas, historiadores, acad\u00e9micos e especialistas africanos, caribenhos e de outras regi\u00f5es do mundo, a fim de consolidar uma posi\u00e7\u00e3o africana unificada sobre a justi\u00e7a hist\u00f3rica, repara\u00e7\u00f5es, restitui\u00e7\u00e3o do patrim\u00f3nio e preserva\u00e7\u00e3o da mem\u00f3ria colectiva.<\/p>\n\n\n\n<p>Os trabalhos abordar\u00e3o as dimens\u00f5es humanas, culturais, econ\u00f3micas, ambientais e jur\u00eddicas dos crimes coloniais, com foco sobre os traumatismos intergeracionais, a espolia\u00e7\u00e3o e a destrui\u00e7\u00e3o do patrim\u00f3nio cultural africano, a explora\u00e7\u00e3o dos recursos e os modelos econ\u00f3micos injustos herdados do colonialismo, os impactos ambientais, incluindo os ensaios nucleares realizados sobre popula\u00e7\u00f5es africanas bem como as vias jur\u00eddicas que permitam refor\u00e7ar a criminaliza\u00e7\u00e3o do colonialismo e estabelecer um mecanismo africano permanente para as repara\u00e7\u00f5es e a restitui\u00e7\u00e3o.<\/p>\n\n\n\n<p>A Arg\u00e9lia, enquanto pa\u00eds anfitri\u00e3o e precursor, pretende contribuir para o refor\u00e7o da arquitetura africana de justi\u00e7a hist\u00f3rica, oferecendo uma plataforma de di\u00e1logo de alto n\u00edvel destinada a consolidar o reconhecimento internacional dos crimes coloniais e a promover os mecanismos concretos de repara\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Arg\u00e9lia vai acolher, nos dias 30 de Novembro a 1 de Dezembro do corrente ano a Confer\u00eancia Internacional sobre os Crimes do Colonialismo em \u00c1frica. Segundo um comunicado de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-9471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/comments?post=9471"}],"version-history":[{"count":2,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9471\/revisions"}],"predecessor-version":[{"id":9473,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/posts\/9471\/revisions\/9473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media\/9474"}],"wp:attachment":[{"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/media?parent=9471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/categories?post=9471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zango.co.ao\/index.php\/wp-json\/wp\/v2\/tags?post=9471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}